{"id":21,"count":1,"description":"","link":"https:\/\/lmintelligence.com\/en\/category\/casos-de-exito\/","name":"SUCCESS STORIES","slug":"casos-de-exito","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casos de \u00c9xito Archives - Legal Machine Intelligence<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lmintelligence.com\/en\/category\/casos-de-exito\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casos de \u00c9xito Archives - Legal Machine Intelligence\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lmintelligence.com\/en\/category\/casos-de-exito\/\" \/>\n<meta property=\"og:site_name\" content=\"Legal Machine Intelligence\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lmintelligence.com\\\/category\\\/casos-de-exito\\\/\",\"url\":\"https:\\\/\\\/lmintelligence.com\\\/category\\\/casos-de-exito\\\/\",\"name\":\"Casos de \u00c9xito Archives - Legal Machine Intelligence\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lmintelligence.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lmintelligence.com\\\/category\\\/casos-de-exito\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lmintelligence.com\\\/category\\\/casos-de-exito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lmintelligence.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casos de \u00c9xito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lmintelligence.com\\\/#website\",\"url\":\"https:\\\/\\\/lmintelligence.com\\\/\",\"name\":\"Legal Machine Intelligence\",\"description\":\"Legal Automation Software\",\"publisher\":{\"@id\":\"https:\\\/\\\/lmintelligence.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lmintelligence.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lmintelligence.com\\\/#organization\",\"name\":\"Legal Machine Intelligence\",\"url\":\"https:\\\/\\\/lmintelligence.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lmintelligence.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lmintelligence.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/LegalMachine_logo-05.png\",\"contentUrl\":\"https:\\\/\\\/lmintelligence.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/LegalMachine_logo-05.png\",\"width\":601,\"height\":239,\"caption\":\"Legal Machine Intelligence\"},\"image\":{\"@id\":\"https:\\\/\\\/lmintelligence.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casos de \u00c9xito Archives - Legal Machine Intelligence","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lmintelligence.com\/en\/category\/casos-de-exito\/","og_locale":"en_US","og_type":"article","og_title":"Casos de \u00c9xito Archives - Legal Machine Intelligence","og_url":"https:\/\/lmintelligence.com\/en\/category\/casos-de-exito\/","og_site_name":"Legal Machine Intelligence","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lmintelligence.com\/category\/casos-de-exito\/","url":"https:\/\/lmintelligence.com\/category\/casos-de-exito\/","name":"Casos de \u00c9xito Archives - Legal Machine Intelligence","isPartOf":{"@id":"https:\/\/lmintelligence.com\/#website"},"breadcrumb":{"@id":"https:\/\/lmintelligence.com\/category\/casos-de-exito\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/lmintelligence.com\/category\/casos-de-exito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lmintelligence.com\/"},{"@type":"ListItem","position":2,"name":"Casos de \u00c9xito"}]},{"@type":"WebSite","@id":"https:\/\/lmintelligence.com\/#website","url":"https:\/\/lmintelligence.com\/","name":"Legal Machine Intelligence","description":"Legal Automation Software","publisher":{"@id":"https:\/\/lmintelligence.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lmintelligence.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lmintelligence.com\/#organization","name":"Legal Machine Intelligence","url":"https:\/\/lmintelligence.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lmintelligence.com\/#\/schema\/logo\/image\/","url":"https:\/\/lmintelligence.com\/wp-content\/uploads\/2024\/07\/LegalMachine_logo-05.png","contentUrl":"https:\/\/lmintelligence.com\/wp-content\/uploads\/2024\/07\/LegalMachine_logo-05.png","width":601,"height":239,"caption":"Legal Machine Intelligence"},"image":{"@id":"https:\/\/lmintelligence.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lmintelligence.com\/en\/wp-json\/wp\/v2\/categories\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lmintelligence.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lmintelligence.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lmintelligence.com\/en\/wp-json\/wp\/v2\/posts?categories=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}